{"id":502,"date":"2022-03-18T02:15:35","date_gmt":"2022-03-18T02:15:35","guid":{"rendered":"https:\/\/sapsa.cr\/?p=502"},"modified":"2022-03-20T15:12:03","modified_gmt":"2022-03-20T15:12:03","slug":"expo-san-carlos-2022","status":"publish","type":"post","link":"https:\/\/sapsa.cr\/index.php\/2022\/03\/18\/expo-san-carlos-2022\/","title":{"rendered":"Expo San Carlos 2022"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"504\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0131-576x1024.jpg\" alt=\"\" class=\"wp-image-504\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0131-576x1024.jpg 576w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0131-169x300.jpg 169w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0131-600x1066.jpg 600w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0131.jpg 633w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"633\" height=\"1125\" data-id=\"503\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0132.jpg\" alt=\"\" class=\"wp-image-503\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0132.jpg 633w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0132-169x300.jpg 169w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0132-576x1024.jpg 576w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0132-600x1066.jpg 600w\" sizes=\"auto, (max-width: 633px) 100vw, 633px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 720 \/ 720;\" width=\"720\" controls src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/InShot_20220319_231628849.mp4\"><\/video><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"618\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-521\" data-id=\"521\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0081-618x1024.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0081-618x1024.jpg 618w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0081-181x300.jpg 181w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0081-600x994.jpg 600w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220318-WA0081.jpg 679w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-517\" data-id=\"517\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220317_180924-1024x768.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220317_180924-1024x768.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220317_180924-300x225.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220317_180924-768x576.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220317_180924-1536x1152.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220317_180924-2048x1536.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220317_180924-1320x990.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220317_180924-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-512\" data-id=\"512\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220319-WA0038-1024x576.jpeg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220319-WA0038-1024x576.jpeg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220319-WA0038-300x169.jpeg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220319-WA0038-768x432.jpeg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220319-WA0038-1536x864.jpeg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220319-WA0038-2048x1152.jpeg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220319-WA0038-1320x743.jpeg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220319-WA0038-600x338.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-520\" data-id=\"520\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220318_200339-768x1024.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220318_200339-768x1024.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220318_200339-225x300.jpg 225w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220318_200339-1152x1536.jpg 1152w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220318_200339-1536x2048.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220318_200339-1320x1760.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220318_200339-600x800.jpg 600w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220318_200339-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-523\" data-id=\"523\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125202-1024x768.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125202-1024x768.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125202-300x225.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125202-768x576.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125202-1536x1152.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125202-2048x1536.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125202-1320x990.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125202-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-524\" data-id=\"524\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125218-1024x768.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125218-1024x768.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125218-300x225.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125218-768x576.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125218-1536x1152.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125218-2048x1536.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125218-1320x990.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125218-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-525\" data-id=\"525\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125235-1024x768.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125235-1024x768.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125235-300x225.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125235-768x576.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125235-1536x1152.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125235-2048x1536.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125235-1320x990.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125235-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-526\" data-id=\"526\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125246-1024x768.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125246-1024x768.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125246-300x225.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125246-768x576.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125246-1536x1152.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125246-2048x1536.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125246-1320x990.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125246-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-527\" data-id=\"527\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125302-1024x768.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125302-1024x768.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125302-300x225.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125302-768x576.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125302-1536x1152.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125302-2048x1536.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125302-1320x990.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125302-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-528\" data-id=\"528\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125320-1024x768.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125320-1024x768.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125320-300x225.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125320-768x576.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125320-1536x1152.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125320-2048x1536.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125320-1320x990.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_125320-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-530\" data-id=\"530\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_152402-768x1024.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_152402-768x1024.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_152402-225x300.jpg 225w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_152402-1152x1536.jpg 1152w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_152402-1536x2048.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_152402-1320x1760.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_152402-600x800.jpg 600w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_152402-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-531\" data-id=\"531\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_160155-1024x768.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_160155-1024x768.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_160155-300x225.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_160155-768x576.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_160155-1536x1152.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_160155-2048x1536.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_160155-1320x990.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_160155-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-532\" data-id=\"532\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_203317-1024x461.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_203317-1024x461.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_203317-300x135.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_203317-768x346.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_203317-1536x691.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_203317-2048x922.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_203317-1320x594.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_203317-600x270.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"461\" height=\"1024\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-533\" data-id=\"533\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_211310-461x1024.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_211310-461x1024.jpg 461w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_211310-135x300.jpg 135w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_211310-768x1707.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_211310-691x1536.jpg 691w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_211310-922x2048.jpg 922w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_211310-1320x2933.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_211310-600x1333.jpg 600w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_211310-scaled.jpg 1152w\" sizes=\"(max-width: 461px) 100vw, 461px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-534\" data-id=\"534\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_212704-1024x461.jpg\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_212704-1024x461.jpg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_212704-300x135.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_212704-768x346.jpg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_212704-1536x691.jpg 1536w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_212704-2048x922.jpg 2048w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_212704-1320x594.jpg 1320w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/20220319_212704-600x270.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/IMG-20220317-WA0131.jpg","_links":{"self":[{"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/posts\/502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/comments?post=502"}],"version-history":[{"count":4,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/posts\/502\/revisions"}],"predecessor-version":[{"id":537,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/posts\/502\/revisions\/537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/media\/504"}],"wp:attachment":[{"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/media?parent=502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/categories?post=502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/tags?post=502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}