{"id":335,"date":"2022-03-05T23:56:31","date_gmt":"2022-03-05T23:56:31","guid":{"rendered":"https:\/\/sapsa.cr\/?p=335"},"modified":"2022-03-06T00:08:32","modified_gmt":"2022-03-06T00:08:32","slug":"calibracion-de-tolva","status":"publish","type":"post","link":"https:\/\/sapsa.cr\/index.php\/2022\/03\/05\/calibracion-de-tolva\/","title":{"rendered":"Mantenimiento y Calibraci\u00f3n de tolva."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Mantenimiento:<\/strong> Verificaci\u00f3n de resistencia \u00d3hmica, milivoltios, revisi\u00f3n del estado de los cables, caja de sumas y comprobaci\u00f3n de peso con 2800kg. Verificaci\u00f3n del indicador de peso, funciones, estado de componentes electr\u00f3nicos y filtros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Calibraci\u00f3n: <\/strong>La\u00a0<strong>calibraci\u00f3n<\/strong>\u00a0es el proceso de comparar los valores obtenidos por un\u00a0<a href=\"https:\/\/es.wikipedia.org\/wiki\/Instrumento_de_medici%C3%B3n\" target=\"_blank\" rel=\"noreferrer noopener\">instrumento de medici\u00f3n<\/a>\u00a0con la medida correspondiente de un patr\u00f3n de referencia (o est\u00e1ndar).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/232991470_4394374703987493_6715433231769431364_n.jpg\" alt=\"\" class=\"wp-image-337\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/232991470_4394374703987493_6715433231769431364_n.jpg 720w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/232991470_4394374703987493_6715433231769431364_n-300x225.jpg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/232991470_4394374703987493_6715433231769431364_n-600x450.jpg 600w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2021-07-06-at-4.50.14-PM-1.jpeg\" alt=\"\" class=\"wp-image-338\" srcset=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2021-07-06-at-4.50.14-PM-1.jpeg 1024w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2021-07-06-at-4.50.14-PM-1-300x225.jpeg 300w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2021-07-06-at-4.50.14-PM-1-768x576.jpeg 768w, https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2021-07-06-at-4.50.14-PM-1-600x450.jpeg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"640\" style=\"aspect-ratio: 640 \/ 640;\" width=\"640\" controls src=\"https:\/\/sapsa.cr\/wp-content\/uploads\/2022\/03\/video.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Mantenimiento: Verificaci\u00f3n de resistencia \u00d3hmica, milivoltios, revisi\u00f3n del estado de los cables, caja de sumas y comprobaci\u00f3n de peso con 2800kg. Verificaci\u00f3n del indicador de peso, funciones, estado de componentes electr\u00f3nicos y filtros. Calibraci\u00f3n: La\u00a0calibraci\u00f3n\u00a0es el proceso de comparar los valores obtenidos por un\u00a0instrumento de medici\u00f3n\u00a0con la medida correspondiente de un patr\u00f3n de referencia (o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-335","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/posts\/335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/comments?post=335"}],"version-history":[{"count":6,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/posts\/335\/revisions"}],"predecessor-version":[{"id":345,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/posts\/335\/revisions\/345"}],"wp:attachment":[{"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/media?parent=335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/categories?post=335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sapsa.cr\/index.php\/wp-json\/wp\/v2\/tags?post=335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}